{"id":160,"date":"2012-05-23T13:20:31","date_gmt":"2012-05-23T16:20:31","guid":{"rendered":"http:\/\/170.210.81.106\/cehepyc\/2012\/05\/23\/integrantes-del-centro\/"},"modified":"2012-05-23T13:20:31","modified_gmt":"2012-05-23T16:20:31","slug":"integrantes-del-centro","status":"publish","type":"post","link":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/integrantes-del-centro\/","title":{"rendered":"Integrantes del Centro"},"content":{"rendered":"<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Orietta Favaro&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:oriettafavaro@speedy.com.ar\">oriettafavaro@speedy.com.ar<\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Profesora y Licenciada en Historia, Universidad Nacional del Comahue (UNCo). Doctora en Historia (UNLP). Docente de la Facultad de Humanidades- Facultad de Derecho y Ciencias Sociales e investigadora de la FAHU- Cehepyc\/CLACSO. Investigadora en Grupos de Trabajo del Consejo Latinoamericano de Ciencias Sociales (Clacso). Realiz&oacute; numerosos estudios publicados en libros y revistas, nacionales e internacionales, vinculados a la historia pol&iacute;tica nacional y local,&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">adem&aacute;s de trabajos sobre el conflicto y la protesta en Argentina.&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Es directora de becarios de iniciaci&oacute;n y posgrado (Secretar&iacute;a de Investigaci&oacute;n, UNCo) y becarios doctorales en el Conicet.&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Dicta seminarios de grado y de posgrado. Dirige tesis de posgrado en el pa&iacute;s y en el exterior.&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Participa en la evaluaci&oacute;n y direcci&oacute;n de publicaciones. Integra comisiones de evaluaci&oacute;n en Argentina.&nbsp;<a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-FAVARO-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Graciela Iuorno&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:gracielaiuorno@gmail.com\">gracielaiuorno@gmail.com<\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Profesora y Licenciada en Historia, Universidad Nacional del Comahue. Mag&iacute;ster en Educaci&oacute;n Superior, UNCo. Doctoranda por la UNCentro, PBA, Tandil. Docente el Area Universal e investigadora en de la Facultad de Humanidades-Cehepyc\/CLACSO. Investigadora en Grupos de Trabajo del Consejo Latinoamericano de Ciencias Sociales. Participa en congresos de la disciplina y cuenta con importantes trabajos en libros y revistas, tanto en el pa&iacute;s como en el extranjero. Dirige tesis de grado y posgrado. Coordin&oacute; con Edda Crespo el libro Nuevos Espacios, Nuevos Problemas. Los Territorios Nacionales, CehepyC-UNCo-UNPSJB.&nbsp;<a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/cv_iuorno2014.pdf\">Click aqu&iacute; para ver CV completo.<\/a><\/span><\/p>\n<div class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Fernando Liz&aacute;rraga&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:falizarraga@yahoo.com.ar\">falizarraga@yahoo.com.ar<\/a>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/span><\/div>\n<div class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"> <\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:falizarraga@conicet.gov.ar\">falizarraga@conicet.gov.ar<\/a><\/span><\/div>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Investigador adjunto del Consejo Nacional de Investigaciones Cient&iacute;ficas y T&eacute;cnicas (CONICET).&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Su plan de trabajo 2012-2013 se titula \u00abActualidad y perspectivas del igualitarismo en la teor&iacute;a pol&iacute;tica contempor&aacute;nea\u00bb. Profesor en Historia por Universidad Nacional del Litoral; Master of Arts en Filosof&iacute;a Pol&iacute;tica, University of York, Inglaterra; Doctor en Ciencias Sociales, Universidad de Buenos Aires. Se desempe&ntilde;a como director y co-director de becarixs doctorales del CONICET. Es coautor de Las Vacas de M&iacute;ster Darwin, y otros ensayos (General Roca: Publifadecs, 2005) y autor de La Justicia en el Pensamiento de Ernesto Che Guevara (La Habana: Editorial de Ciencias Sociales, 2007). Public&oacute; art&iacute;culos y cap&iacute;tulos de libros, en la Argentina y el exterior, sobre filosof&iacute;a pol&iacute;tica contempor&aacute;nea, especialmente en torno al debate entre el marxismo y el igualitarismo liberal. Su blog personal es <a href=\"http:\/\/alephalsur.blogspot.com\">http:\/\/alephalsur.blogspot.com<\/a>. M&aacute;s informaci&oacute;n curricular puede verse tambi&eacute;n en la p&aacute;gina del CONICET:&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"http:\/\/www.conicet.gov.ar\">www.conicet.gov.ar<\/a>.&nbsp;<\/span><a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/cv_lizrraga2014.pdf\" style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Click aqu&iacute; para ver CV completo<\/a><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">.<\/span><\/p>\n<div class=\"Estilo2\" dir=\"ltr\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Mario Arias Bucciarelli &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; <\/strong><\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:ariasbucciarelli@gmail.com\"><\/a><\/span><\/div>\n<div class=\"Estilo2\" dir=\"ltr\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:ariasbucciarelli@gmail.com\">ariasbucciarelli@gmail.com<\/a><a href=\"mailto:ariasbucciarelli@gmail.com\"><\/a><\/span><\/div>\n<p><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Historiador. Posgraduado en Ciencias Sociales (UFRO\/ Paris XII) y Profesor Regular e Investigador en el Departamento de Historia de la UNCo. Coordina el Grupo de Historia Pol&iacute;tica, dirige la Red de Estudios sobre Territorios Nacionales y es responsable del Nodo Comahue de la Red de Estudios sobre el Peronismo. Desarrolla su tarea docente en la orientaci&oacute;n siglo XX\/XXI del &Aacute;rea Argentina y registra publicaciones(libros, cap&iacute;tulos de libros y en diversas revistas especializadas del pa&iacute;s y del exterior.&nbsp;<a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-ARIASB-CV.pdf\">Click aqu&iacute; para ver CV completo.<\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Mar&iacute;a Elizabeth Vaccarisi&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt; color: #0000ff;\"><a href=\"mailto:marilu2659@hotmail.com\" target=\"_blank\" style=\"color: #1155cc;\" rel=\"noopener\"><span style=\"color: #0000ff;\">mevaccarisi@speedy.com.ar<\/span><\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Licenciada en Servicio Social. Mag&iacute;ster en Metodolog&iacute;a de la Investigaci&oacute;n Cient&iacute;fica y T&eacute;cnica. Profesora del &Aacute;rea Metodol&oacute;gica del Servicio Social de la Facultad de Derecho y Ciencias Sociales (UNCo). Investigadora del Cehepyc\/CLACSO. Realiza docencia de postgrado. Dirige tesis de postgrado y becarios alumnos de investigaci&oacute;n y extensi&oacute;n (UNCo). Autora y co- autora de trabajos vinculados con el Estado, las Pol&iacute;ticas Sociales y la Oposici&oacute;n pol&iacute;tica partidaria. Present&oacute; numerosos estudios en congresos y jornadas de ciencias sociales; cuenta adem&aacute;s con la publicaci&oacute;n de cap&iacute;tulos de libros y de trabajos de difusi&oacute;n masiva. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-VACARISSI-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<div class=\"Estilo2\" align=\"justify\"><strong style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Isabel Edith Salerno<\/strong><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:isabel_salerno@yahoo.com.ar\"><br \/><\/a><\/span><\/div>\n<div class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:isabel_salerno@yahoo.com.ar\">isabel_salerno@yahoo.com.ar<\/a><\/span><\/div>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Licenciada en Ciencias de la Informaci&oacute;n UNC. Mag&iacute;ster en Gesti&oacute;n Ambiental del Desarrollo Urbano UNCo. Doctoranda en Comunicaci&oacute;n Social UNC. Profesora del &Aacute;rea Audiovisual &#8211; Comunicaci&oacute;n Social- Facultad de Derecho y Ciencias Sociales (UNCo). Investigadora del Cehepyc\/CLACSO. Dirige tesis de grado, becarios alumnos de extensi&oacute;n y de voluntarios del Programa de Voluntariado Universitario (UNCo). Autora de trabajos vinculados a la Problem&aacute;tica ambiental. Autora y co-autora de trabajos vinculados a la Accesibilidad para personas con discapacidad. Present&oacute; estudios en congresos y jornadas de comunicaci&oacute;n; cuenta adem&aacute;s con la publicaci&oacute;n de cap&iacute;tulos de libros. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-SALERNO-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Mar&iacute;a Cecilia Azconegui&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:cazconegui@gmail.com\">cazconegui@gmail.com<\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Profesora en Historia por la Universidad de Buenos Aires. Mag&iacute;ster en Pol&iacute;tica Internacional por la Universidad de Melbourne, Australia. Doctoranda en la Universidad de San Andr&eacute;s, Buenos Aires.&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Docente en el Area Argentina, de la Facultad de Humanidades, Departamento de Historia, UNCo.&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Cuenta con presentaciones a congresos y jornadas, asimismo con publicaciones en el pa&iacute;s y el extranjero. Miembro-investigador del Cehepyc-CLACSO. Reviste con el car&aacute;cter de becaria de perfeccionamiento de la Secretar&iacute;a de Investigaci&oacute;n, UNCo en el per&iacute;odo 2011-2012.&nbsp;<a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-AZCONEGUI-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><strong><span style=\"font-family: tahoma, arial, helvetica, sans-serif;\">Andrea Bel&eacute;n Rodr&iacute;guez<\/span><\/strong><\/span><br \/><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\"><a href=\"mailto:andrea_belen_rodriguez@yahoo.com\">andrea_belen_rodriguez@yahoo.com<\/a><\/span><\/p>\n<p><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Doctora en Historia por la Universidad Nacional de La Plata. Profesora y Licenciada en Historia por la Universidad Nacional del Sur. Es docente en las &Aacute;reas Te&oacute;rica y Argentina Siglo XX en la Universidad Nacional del Comahue. Becaria posdoctoral del CONICET. Ha publicado diversos cap&iacute;tulos y art&iacute;culos en revistas nacionales y extranjeras. Se especializa en Historia Argentina Reciente, espec&iacute;ficamente guerra y posguerra de Malvinas. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-RODRIGUEZ-CV.pdf\">Click aqu&iacute; para ver su CV completo<\/a>.<\/span><\/p>\n<div class=\"Estilo2\" align=\"justify\"><strong style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Mar&iacute;a Emilia Campos&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/strong><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:milinqn@hotmail.com\"><br \/><\/a><\/span><\/div>\n<div class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:milinqn@hotmail.com\">milinqn@hotmail.com<\/a><\/span><\/div>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Licenciada en Servicio Social. Especialista en Derechos del Ni&ntilde;o y Pol&iacute;ticas Publicas para la Infancia y Adolescencia (UNICEF- UNCo.). Especializaci&oacute;n en Derechos Humanos (FADECS &ndash; UNCo). Docente de las c&aacute;tedras Teor&iacute;a y Pr&aacute;ctica de Servicio Social con Grupo de la Facultad de Derecho y Ciencias Sociales (UNCo.). Investigadora del Cehepyc\/CLACSO. Co-autora de trabajos y publicaciones relacionadas al Estado, Pol&iacute;ticas Sociales y la Oposici&oacute;n en el Sistema Democr&aacute;tico y autora de trabajos vinculado con lo grupal. En la actualidad reviste como coordinadora del Departamento de Servicio Social (FADECS) desde agosto 2010. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-CAMPOS-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<p class=\"Estilo2\" style=\"text-align: justify;\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Mar&iacute;a Susana Palacios&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:masusip@hotmail.com\">masusip@hotmail.com<\/a><\/span><\/p>\n<p class=\"Estilo2\" style=\"text-align: justify;\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Profesora en Historia. Docente regular del &Aacute;rea Argentina, Facultad de Humanidades, UNCo. Investigadora. Participa en Jornadas de la disciplina y public&oacute; trabajos sobre cuestiones de la pol&iacute;tica y lo pol&iacute;tico regional, sobre el municipio de Cutral Co como asimismo aspectos pol&iacute;ticos institucionales de la historia de Neuqu&eacute;n en revistas latinoamericanas, nacionales y regionales.<\/span><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\"><\/span><a href=\"http:\/\/investigadores.uncoma.edu.ar\/cehepyc\/CURRICULUMS\/CV%20Palacios.pdf\" style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Click aqu&iacute; para ver CV completo<\/a><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">.<\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Beatriz Carolina Ch&aacute;vez&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:vickycha2003@yahoo.com.ar\">vickycha2003@yahoo.com.ar<\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Profesora y Licenciada en Historia. Docente de Ense&ntilde;anza Media. Desempe&ntilde;&oacute; cargos directivos en escuelas de la provincia y en el CPE. Miembro- investigador del Cehepyc\/ CLACSO. Autora de art&iacute;culos en diarios locales sobre Historia Regional y Vida Cotidiana de los habitantes y personajes de Neuqu&eacute;n. Particip&oacute; con temas vinculados a la Historia Regional (Maestros en el Territorio y en la Provincia ) en las Fasc&iacute;culos editados por el Cehepyc en convenio con un diario neuquino&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">durante el a&ntilde;o 2008. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-CHAVEZ-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<div class=\"Estilo2\" align=\"justify\"><strong style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Suyai Malen Garc&iacute;a Gualda &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/strong><\/div>\n<div class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:gsuyai@hotmail.com\">gsuyai@hotmail.com<\/a><\/span><\/div>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Licenciada en Ciencia Pol&iacute;tica y Administraci&oacute;n P&uacute;blica, graduada de la Universidad Nacional de Cuyo, Mendoza. Diploma Superior en Ciencias Sociales con menci&oacute;n en G&eacute;nero y Pol&iacute;ticas P&uacute;blicas (FLACSO). Tesista de la Maestr&iacute;a en G&eacute;nero, Socidad y Pol&iacute;ticas (FLACSO). Doctoranda en Ciencias Sociales con menci&oacute;n en Ciencia Pol&iacute;tica y Administraci&oacute;n P&uacute;blica (UNCuyo). Becaria doctoral de CONICET (Cehepyc-UNCo\/CONICET). Ayudante de Primera de la c&aacute;tedra de Antropolog&iacute;a Cultural de la carrera de Psicolog&iacute;a en la Universidad Nacional del Comahue. Adscripta <em>ad-honorem<\/em> en la c&aacute;tedra Teor&iacute;a Pol&iacute;tica II de la Licenciatura de Ciencia Pol&iacute;tica y Administraci&oacute;n P&uacute;blica de la Universidad Nacional de Cuyo. Ha participado de diversos eventos cient&iacute;ficos y publicado ponencias y art&iacute;culos sobre sus principales l&iacute;neas de estudio: g&eacute;nero y pueblos originarios. Miembro activo del Cehepyc\/Clacso.&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"http:\/\/investigadores.uncoma.edu.ar\/cehepyc\/CURRICULUMS\/CV_Gualda.pdf\">&nbsp;Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<div><span style=\"font-size: 10pt;\"><strong><span style=\"font-family: tahoma, arial, helvetica, sans-serif;\">Laura F. Duimich<\/span><\/strong><\/span><\/div>\n<div><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">duimich@hotmail.com<\/span><\/div>\n<p><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Lic. en Ciencia Pol&iacute;tica (UBA). Maestranda en Filosof&iacute;a con Orientaci&oacute;n en Filosof&iacute;a Social y Pol&iacute;tica (UNQ). Doctoranda en Ciencias Sociales (UBA). Docente de Sociolog&iacute;a en la Facultad de Ciencias de la Educaci&oacute;n, Universidad Nacional del Comahue. Participa del Proyecto de Investigaci&oacute;n: &ldquo;Poder, actores, disputas y resistencias sociopol&iacute;ticas en la norpatagonia argentina. Neuqu&eacute;n y R&iacute;o Negro, 1983-2013&rdquo; de la UNCo y del Proyecto: \u00abLa justicia social, la igualdad y la comunidad en las hegemon&iacute;as pol&iacute;ticas, las oposiciones partidarias y las resistencias sociales en la Norpatagonia argentina (1983-2011)\u00bb del CONICET.&nbsp;L&iacute;neas de investigaci&oacute;n: Estudios Culturales. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-DUIMICH-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Julieta Sartino&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:sartino84@hotmail.com\">sartino84@hotmail.com<\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Lic. en Ciencia Pol&iacute;tica de la Universidad Nacional de Rosario. Ayudante de primera en la C&aacute;tedra &ldquo;Estado, gobierno y sociedad&rdquo; y en &ldquo;Metodolog&iacute;a de la Investigaci&oacute;n&rdquo; de la Licenciatura en Criminolog&iacute;a y Ciencias Forenses de la Universidad Nacional de R&iacute;o Negro, sede Cipolletti.&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Integrante en car&aacute;cter de miembro activo del CEAPEDI- Centro de Estudios y Actualizaci&oacute;n en Pensamiento Pol&iacute;tico, Decolonialidad e Interculturalidad, de la Facultad de Humanidades de la Universidad Nacional del Comahue; integrante externa del proyecto de investigaci&oacute;n &ldquo;Indagaci&oacute;n cr&iacute;tico-interpelativa del presente. Coordenadas de matrices de pensamiento: hibridaci&oacute;n e interdiscursividad&rdquo;, Universidad Nacional del Comahue (FAHU) y colaboradora del proyecto de investigaci&oacute;n &ldquo;Temas y problemas de la Norpatagonia argentina. Disputas y conflictos&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">sociopol&iacute;ticos en los veinticinco a&ntilde;os de democracia&rdquo;, Cehepyc-Clacso, Facultad de&nbsp;<\/span><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Humanidades, UNCo.&nbsp;<a href=\"http:\/\/investigadores.uncoma.edu.ar\/cehepyc\/CURRICULUMS\/CV%20Sartino.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><strong>Emilia Alfieri&nbsp;<\/strong><\/span><br \/><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:emialfieri@yahoo.com.ar\">emialfieri@yahoo.com.ar<\/a><\/span><\/p>\n<p><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Licenciada en Sociolog&iacute;a (UBA). Magister en Criminolog&iacute;a (UNL). Docente regular y con dedicaci&oacute;n exclusiva del Departamento de Ciencias Pol&iacute;ticas y Sociales de la Facultad de Derecho y Ciencias Sociales, Universidad Nacional del Comahue. Se desempe&ntilde;a como ayudante de primera en materias de las carreras de Sociolog&iacute;a, Psicolog&iacute;a y Servicio Social (UNCo). Coordinadora del Grupo de Estudios Delito y Sociedad (GEDyS) en el marco del Centro de Estudios Hist&oacute;ricos de Estado, Pol&iacute;tica y Cultura (Cehepyc\/CLACSO), integrante docente del Proyecto de Investigaci&oacute;n &ldquo;Poder, actores, disputas y resistencias sociopol&iacute;ticas en la Norpatagonia argentina. Neuqu&eacute;n y R&iacute;o Negro, 1983-2013&rdquo;. Ha participado de diversos eventos cient&iacute;ficos, seminarios y cursos de posgrado relativos a sus principales l&iacute;neas de estudio: sociolog&iacute;a del castigo, organizaciones de v&iacute;ctimas, reclamos de castigo, discursos acerca del delito\/(in)seguridad. Adem&aacute;s ha publicado diversas ponencias y art&iacute;culos sobre dichos temas en revistas especializadas, tales como: Revista Delito y Sociedad, Revista de Derecho Penal y Criminolog&iacute;a, entre otras.&nbsp;<span style=\"font-family: tahoma, arial, helvetica, sans-serif;\"><a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-ALFIERI-CV2.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/span><\/p>\n<div class=\"Estilo2\" align=\"justify\"><strong><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Jes&uacute;s Jaramillo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; <\/span><\/strong><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:jesusnqn@gmail.com\"><br \/><\/a><\/span><\/div>\n<div class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:jesusnqn@gmail.com\">jesusnqn@gmail.com<\/a>&nbsp;<\/span><\/div>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Magister en Investigaci&oacute;n Educativa por el Centro de Estudios Avanzados de la Universidad Nacional de C&oacute;rdoba y Profesor en Ciencias de la Educaci&oacute;n por la Universidad Nacional del Comahue. Actualmente es docente en la misma universidad y becario doctoral del Consejo Nacional de Investigaciones Cient&iacute;ficas y Tecnol&oacute;gicas (CONICET) en el Instituto Patag&oacute;nico de Estudios de Humanidades y Ciencias Sociales (IPEHCS-CONICET-UNCo). Hace diez a&ntilde;os se desempe&ntilde;a como investigador en el campo de la etnograf&iacute;a de la educaci&oacute;n, en particular en asuntos vinculados a procesos de socializaci&oacute;n de ni&ntilde;os, ni&ntilde;as y j&oacute;venes pertenecientes a sectores populares urbanos. Es investigador-miembro del Grupo de Antropolog&iacute;a de la Educaci&oacute;n del Centro de Antropolog&iacute;a Social del Instituto de Desarrollo Econ&oacute;mico y Social (IDES) y de la Red Internacional de Etnograf&iacute;a con Ni&ntilde;os, Ni&ntilde;as y Adolescentes (RIENN).&nbsp;<a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/cv_jaramillo_2013.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n<div class=\"Estilo2\" align=\"justify\"><strong><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Marina Anderson &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/span><\/strong><\/div>\n<div class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\"><a href=\"mailto:marinanderson@hotmail.com\">msandersonp@gmail.com<\/a><\/span><\/div>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma,arial,helvetica,sans-serif; font-size: 10pt;\">Licenciada en Ciencia Pol&iacute;tica de la Universidad de Buenos Aires (UBA), recibida con diploma de honor, y maestranda en Ciencias Sociales y Humanidades por la Universidad Nacional de Quilmes (UNQUI). Doctoranda en Ciencias Sociales por la Universidad de Buenos Aires (UBA). Becaria doctoral del Consejo Nacional de Investigaciones Cient&iacute;ficas y T&eacute;cnicas (CONICET) en el Instituto Patag&oacute;nico de Estudios de Humanidades y Ciencias Sociales (IPEHCS), con el proyecto: &ldquo;Las actividades hidrocarbur&iacute;feras en la provincia de Neuqu&eacute;n: intervenci&oacute;n de los organismos p&uacute;blicos y agencias estatales en la gesti&oacute;n del medio ambiente, 1990-2013&rdquo;. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/cv_anderson2014.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\"><span style=\"font-family: 'Times New Roman', serif; font-size: 12pt;\"><\/span><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\"><strong>Santiago Gin&eacute;s Nabaes Jodar<\/strong><br \/><a href=\"mailto:santiagonabaes@gmail.com\">santiagonabaes@gmail.com<\/a><\/span><\/p>\n<p class=\"Estilo2\" align=\"justify\"><span style=\"font-family: tahoma, arial, helvetica, sans-serif; font-size: 10pt;\">Abogado (Fadecs-UNCo). Tesista en la Maestr&iacute;a en Criminolog&iacute;a Maestr&iacute;a en Criminolog&iacute;a, Facultad de Ciencias Jur&iacute;dicas y Sociales (Universidad Nacional del Litoral) y Facultad de Derecho y Ciencias Sociales (Universidad Nacional del Comahue). Es becario doctoral del CONICET. Posee antecedentes en docencia universitaria y ha participado en cursos, jornadas y congreso. Integra un proyecto de investigaci&oacute;n en le Cehepyc. <a href=\"https:\/\/cehepyc.uncoma.edu.ar\/wp-content\/uploads\/2012\/05\/2017-NABAES-CV.pdf\">Click aqu&iacute; para ver CV completo<\/a>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orietta Favaro&nbsp;oriettafavaro@speedy.com.ar Profesora y Licenciada en Historia, Universidad Nacional del Comahue (UNCo). Doctora en Historia (UNLP). Docente de la Facultad de Humanidades- Facultad de Derecho y Ciencias Sociales e investigadora de la FAHU- Cehepyc\/CLACSO. Investigadora en Grupos de Trabajo del Consejo Latinoamericano de Ciencias Sociales (Clacso). Realiz&oacute; numerosos estudios publicados en libros y revistas, nacionales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integrantes-del-centro"],"_links":{"self":[{"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":0,"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/2294"}],"wp:attachment":[{"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cehepyc.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}